{"id":100,"date":"2018-02-06T10:46:57","date_gmt":"2018-02-06T10:46:57","guid":{"rendered":"http:\/\/bridge154.qodeinteractive.com\/?page_id=100"},"modified":"2026-03-09T09:18:59","modified_gmt":"2026-03-09T08:18:59","slug":"our-projects","status":"publish","type":"page","link":"https:\/\/www.frapont.es\/es\/our-projects\/","title":{"rendered":"Proyectos"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbfull_width\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb z_index=\u00bb\u00bb][vc_column]<div class=\"qode-advanced-tabs qode-advanced-tabs qode-advanced-horizontal-tab clearfix qode-advanced-tab-with-icon qode-advanced-tabs-column-3 clearfix\">\n\t<ul class=\"qode-advanced-tabs-nav\">\n\t\t\t\t\t<li>\n\t\t\t\t<h4>\n\t\t\t\t\t<a href=\"#tab-imagenes\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"qode-advanced-icon-frame\"><\/span>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"qode-advanced-tab-text-after-icon\">\n\t\t\t\t\t\t\t\tIMAGENES\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t<\/li>\n\t\t\t\t\t<li>\n\t\t\t\t<h4>\n\t\t\t\t\t<a href=\"#tab-lista\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"qode-advanced-icon-frame\"><\/span>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"qode-advanced-tab-text-after-icon\">\n\t\t\t\t\t\t\t\tLISTA\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t<\/li>\n\t\t\t\t\t<li>\n\t\t\t\t<h4>\n\t\t\t\t\t<a href=\"#tab-mapa\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"qode-advanced-icon-frame\"><\/span>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"qode-advanced-tab-text-after-icon\">\n\t\t\t\t\t\t\t\tMAPA\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t<\/li>\n\t\t\t<\/ul>\n\t<div class=\"qode-advanced-tab-container\" id=\"tab-imagenes-522\" data-icon-pack=\"font_awesome\" data-icon-html=\"&lt;i class=&quot;qode_icon_font_awesome fa fa-picture-o &quot; &gt;&lt;\/i&gt;\">[vc_empty_space height=\u00bb20px\u00bb]<div class='projects_holder_outer v4 portfolio_with_space portfolio_standard'><div class='filter_outer'><div class='filter_holder'>\n                            <ul>\n                            <li class='filter' data-filter='all'><span style='color:#9a9a9a'>All<\/span><\/li><li class='filter' data-filter='portfolio_category_111'><span style='color:#9a9a9a'>Auditorios<\/span><\/li><li class='filter' data-filter='portfolio_category_80'><span style='color:#9a9a9a'>Cultural<\/span><\/li><li class='filter' data-filter='portfolio_category_5'><span style='color:#9a9a9a'>Dinamarca<\/span><\/li><li class='filter' data-filter='portfolio_category_6'><span style='color:#9a9a9a'>Espa\u00f1a<\/span><\/li><li class='filter' data-filter='portfolio_category_7'><span style='color:#9a9a9a'>Francia<\/span><\/li><li class='filter' data-filter='portfolio_category_14'><span style='color:#9a9a9a'>Hoteles<\/span><\/li><li class='filter' data-filter='portfolio_category_15'><span style='color:#9a9a9a'>Institucional<\/span><\/li><li class='filter' data-filter='portfolio_category_8'><span style='color:#9a9a9a'>Montenegro<\/span><\/li><li class='filter' data-filter='portfolio_category_9'><span style='color:#9a9a9a'>Noruega<\/span><\/li><li class='filter' data-filter='portfolio_category_13'><span style='color:#9a9a9a'>Oficinas<\/span><\/li><li class='filter' data-filter='portfolio_category_10'><span style='color:#9a9a9a'>Suecia<\/span><\/li><li class='filter' data-filter='portfolio_category_130'><span style='color:#9a9a9a'>Suministro<\/span><\/li><li class='filter' data-filter='portfolio_category_11'><span style='color:#9a9a9a'>UK<\/span><\/li><\/ul><\/div><\/div><div class='projects_holder portfolio_main_holder clearfix v4 standard portfolio_full_image '>\n<article class='mix portfolio_category_5 portfolio_category_13 portfolio_category_130 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/suministro-paneles-acusticos-madera-copenhague\/' target='_self'><span class='image'><img fetchpriority=\"high\" decoding=\"async\" width=\"1120\" height=\"1120\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/07\/APPENSION_FRAPONT_5_web.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/07\/APPENSION_FRAPONT_5_web.jpg 1120w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/07\/APPENSION_FRAPONT_5_web-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/07\/APPENSION_FRAPONT_5_web-1024x1024.jpg 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/07\/APPENSION_FRAPONT_5_web-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/07\/APPENSION_FRAPONT_5_web-768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/07\/APPENSION_FRAPONT_5_web-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/07\/APPENSION_FRAPONT_5_web-500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/07\/APPENSION_FRAPONT_5_web-1000x1000.jpg 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/07\/APPENSION_FRAPONT_5_web-700x700.jpg 700w\" sizes=\"(max-width: 1120px) 100vw, 1120px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/suministro-paneles-acusticos-madera-copenhague\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/suministro-paneles-acusticos-madera-copenhague\/\" style=\"color: #575959\" target=\"_self\">AP PENSION &#038; NYKREDIT<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_9 portfolio_category_13 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/escaleras-interiores-gnist-stavanger\/' target='_self'><span class='image'><img decoding=\"async\" width=\"2560\" height=\"2560\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/02\/1x1-web-scaled.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/02\/1x1-web-scaled.jpg 2560w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/02\/1x1-web-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/02\/1x1-web-1024x1024.jpg 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/02\/1x1-web-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/02\/1x1-web-768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/02\/1x1-web-1536x1536.jpg 1536w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/02\/1x1-web-2048x2048.jpg 2048w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/02\/1x1-web-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/02\/1x1-web-500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/02\/1x1-web-1000x1000.jpg 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/02\/1x1-web-700x700.jpg 700w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" loading=\"lazy\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/escaleras-interiores-gnist-stavanger\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/escaleras-interiores-gnist-stavanger\/\" style=\"color: #575959\" target=\"_self\">GNIST<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_111 portfolio_category_80 portfolio_category_9 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/proyectos-revestimientos-acusticos-de-madera\/' target='_self'><span class='image'><img decoding=\"async\" width=\"1331\" height=\"1331\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/02\/Miniatura.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/02\/Miniatura.jpg 1331w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/02\/Miniatura-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/02\/Miniatura-1024x1024.jpg 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/02\/Miniatura-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/02\/Miniatura-768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/02\/Miniatura-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/02\/Miniatura-500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/02\/Miniatura-1000x1000.jpg 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/02\/Miniatura-700x700.jpg 700w\" sizes=\"(max-width: 1331px) 100vw, 1331px\" loading=\"lazy\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/proyectos-revestimientos-acusticos-de-madera\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/proyectos-revestimientos-acusticos-de-madera\/\" style=\"color: #575959\" target=\"_self\">NORMORIA<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_6 portfolio_category_13 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/proyectos-soluciones-tecnicas-a-medida-edificio-estel\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1302\" height=\"1302\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/01\/portada-web.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/01\/portada-web.jpg 1302w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/01\/portada-web-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/01\/portada-web-1024x1024.jpg 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/01\/portada-web-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/01\/portada-web-768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/01\/portada-web-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/01\/portada-web-500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/01\/portada-web-1000x1000.jpg 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/01\/portada-web-700x700.jpg 700w\" sizes=\"(max-width: 1302px) 100vw, 1302px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/proyectos-soluciones-tecnicas-a-medida-edificio-estel\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/proyectos-soluciones-tecnicas-a-medida-edificio-estel\/\" style=\"color: #575959\" target=\"_self\">ESTEL BARCELONA<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_80 portfolio_category_9 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/aahka-de-outi-pieski\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1578\" height=\"1577\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2025\/12\/Rasmus_Hjortshoj__Regjeringkvartalet_WEB-40_portada.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2025\/12\/Rasmus_Hjortshoj__Regjeringkvartalet_WEB-40_portada.png 1578w, https:\/\/www.frapont.es\/wp-content\/uploads\/2025\/12\/Rasmus_Hjortshoj__Regjeringkvartalet_WEB-40_portada-300x300.png 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2025\/12\/Rasmus_Hjortshoj__Regjeringkvartalet_WEB-40_portada-1024x1024.png 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2025\/12\/Rasmus_Hjortshoj__Regjeringkvartalet_WEB-40_portada-150x150.png 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2025\/12\/Rasmus_Hjortshoj__Regjeringkvartalet_WEB-40_portada-768x768.png 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2025\/12\/Rasmus_Hjortshoj__Regjeringkvartalet_WEB-40_portada-1536x1536.png 1536w, https:\/\/www.frapont.es\/wp-content\/uploads\/2025\/12\/Rasmus_Hjortshoj__Regjeringkvartalet_WEB-40_portada-570x570.png 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2025\/12\/Rasmus_Hjortshoj__Regjeringkvartalet_WEB-40_portada-500x500.png 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2025\/12\/Rasmus_Hjortshoj__Regjeringkvartalet_WEB-40_portada-1000x1000.png 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2025\/12\/Rasmus_Hjortshoj__Regjeringkvartalet_WEB-40_portada-700x700.png 700w\" sizes=\"(max-width: 1578px) 100vw, 1578px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/aahka-de-outi-pieski\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/aahka-de-outi-pieski\/\" style=\"color: #575959\" target=\"_self\">&#8216;AAhkA&#8217; DE OUTI PIESKI<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_9 portfolio_category_13 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/interiores-de-madera-en-construction-city-oslo\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1707\" height=\"1707\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2025\/11\/ConstructionCity04-1-scaled-e1763551218298.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2025\/11\/ConstructionCity04-1-scaled-e1763551218298.jpg 1707w, https:\/\/www.frapont.es\/wp-content\/uploads\/2025\/11\/ConstructionCity04-1-scaled-e1763551218298-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2025\/11\/ConstructionCity04-1-scaled-e1763551218298-1024x1024.jpg 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2025\/11\/ConstructionCity04-1-scaled-e1763551218298-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2025\/11\/ConstructionCity04-1-scaled-e1763551218298-768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2025\/11\/ConstructionCity04-1-scaled-e1763551218298-1536x1536.jpg 1536w, https:\/\/www.frapont.es\/wp-content\/uploads\/2025\/11\/ConstructionCity04-1-scaled-e1763551218298-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2025\/11\/ConstructionCity04-1-scaled-e1763551218298-500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2025\/11\/ConstructionCity04-1-scaled-e1763551218298-1000x1000.jpg 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2025\/11\/ConstructionCity04-1-scaled-e1763551218298-700x700.jpg 700w\" sizes=\"(max-width: 1707px) 100vw, 1707px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/interiores-de-madera-en-construction-city-oslo\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/interiores-de-madera-en-construction-city-oslo\/\" style=\"color: #575959\" target=\"_self\">CONSTRUCTION CITY<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_15 portfolio_category_10 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/skane-university-hospital-campus\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/05\/Cover.webp\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/05\/Cover.webp 1080w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/05\/Cover-300x300.webp 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/05\/Cover-1024x1024.webp 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/05\/Cover-150x150.webp 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/05\/Cover-768x768.webp 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/05\/Cover-570x570.webp 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/05\/Cover-500x500.webp 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/05\/Cover-1000x1000.webp 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/05\/Cover-700x700.webp 700w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/skane-university-hospital-campus\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/skane-university-hospital-campus\/\" style=\"color: #575959\" target=\"_self\">SK\u00c5NE UNIVERSITY HOSPITAL CAMPUS<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_5 portfolio_category_14 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/25-hours-copenague\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/08\/cover.webp\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/08\/cover.webp 1080w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/08\/cover-300x300.webp 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/08\/cover-1024x1024.webp 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/08\/cover-150x150.webp 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/08\/cover-768x768.webp 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/08\/cover-570x570.webp 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/08\/cover-500x500.webp 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/08\/cover-1000x1000.webp 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/08\/cover-700x700.webp 700w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/25-hours-copenague\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/25-hours-copenague\/\" style=\"color: #575959\" target=\"_self\">25 HOURS COPENAGUE<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_6 portfolio_category_14 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/formentor\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"2560\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/10\/Cover-Formentor-scaled.webp\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/10\/Cover-Formentor-scaled.webp 2560w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/10\/Cover-Formentor-300x300.webp 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/10\/Cover-Formentor-1024x1024.webp 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/10\/Cover-Formentor-150x150.webp 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/10\/Cover-Formentor-768x768.webp 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/10\/Cover-Formentor-1536x1536.webp 1536w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/10\/Cover-Formentor-2048x2048.webp 2048w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/10\/Cover-Formentor-570x570.webp 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/10\/Cover-Formentor-500x500.webp 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/10\/Cover-Formentor-1000x1000.webp 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/10\/Cover-Formentor-700x700.webp 700w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/formentor\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/formentor\/\" style=\"color: #575959\" target=\"_self\">FORMENTOR<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_6 portfolio_category_14 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/westin-palace\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1279\" height=\"1279\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/10\/Cuadrada.webp\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/10\/Cuadrada.webp 1279w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/10\/Cuadrada-300x300.webp 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/10\/Cuadrada-1024x1024.webp 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/10\/Cuadrada-150x150.webp 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/10\/Cuadrada-768x768.webp 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/10\/Cuadrada-570x570.webp 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/10\/Cuadrada-500x500.webp 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/10\/Cuadrada-1000x1000.webp 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/10\/Cuadrada-700x700.webp 700w\" sizes=\"(max-width: 1279px) 100vw, 1279px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/westin-palace\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/westin-palace\/\" style=\"color: #575959\" target=\"_self\">WESTIN PALACE<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_7 portfolio_category_15 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/palau_valencia-copy\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/08\/COVERI.webp\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/08\/COVERI.webp 1080w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/08\/COVERI-300x300.webp 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/08\/COVERI-1024x1024.webp 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/08\/COVERI-150x150.webp 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/08\/COVERI-768x768.webp 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/08\/COVERI-570x570.webp 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/08\/COVERI-500x500.webp 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/08\/COVERI-1000x1000.webp 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/08\/COVERI-700x700.webp 700w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/palau_valencia-copy\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/palau_valencia-copy\/\" style=\"color: #575959\" target=\"_self\">SAINT-DENIS PLEYEL STATION<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_111 portfolio_category_80 portfolio_category_6 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/palau-de-valencia\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/11\/Palau-de-valencia-Cuadrada.webp\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/11\/Palau-de-valencia-Cuadrada.webp 1080w, https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/11\/Palau-de-valencia-Cuadrada-300x300.webp 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/11\/Palau-de-valencia-Cuadrada-1024x1024.webp 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/11\/Palau-de-valencia-Cuadrada-150x150.webp 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/11\/Palau-de-valencia-Cuadrada-768x768.webp 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/11\/Palau-de-valencia-Cuadrada-570x570.webp 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/11\/Palau-de-valencia-Cuadrada-500x500.webp 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/11\/Palau-de-valencia-Cuadrada-1000x1000.webp 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/11\/Palau-de-valencia-Cuadrada-700x700.webp 700w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/palau-de-valencia\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/palau-de-valencia\/\" style=\"color: #575959\" target=\"_self\">PALAU DE VALENCIA<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_7 portfolio_category_14 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-carlton-cannes\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/05\/Square-2.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/05\/Square-2.jpg 1080w, https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/05\/Square-2-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/05\/Square-2-1024x1024.jpg 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/05\/Square-2-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/05\/Square-2-768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/05\/Square-2-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/05\/Square-2-500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/05\/Square-2-1000x1000.jpg 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/05\/Square-2-700x700.jpg 700w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-carlton-cannes\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-carlton-cannes\/\" style=\"color: #575959\" target=\"_self\">HOTEL CARLTON CANNES<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_111 portfolio_category_7 portfolio_category_13 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/tour-hekla\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/12\/Hekla-.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/12\/Hekla-.jpg 1080w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/12\/Hekla--300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/12\/Hekla--1024x1024.jpg 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/12\/Hekla--150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/12\/Hekla--768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/12\/Hekla--570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/12\/Hekla--500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/12\/Hekla--1000x1000.jpg 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/12\/Hekla--700x700.jpg 700w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/tour-hekla\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/tour-hekla\/\" style=\"color: #575959\" target=\"_self\">TORRE HEKLA<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_15 portfolio_category_11 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/cavendish-sfh\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/01\/C.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/01\/C.jpg 1080w, https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/01\/C-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/01\/C-1024x1024.jpg 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/01\/C-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/01\/C-768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/01\/C-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/01\/C-500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/01\/C-1000x1000.jpg 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/01\/C-700x700.jpg 700w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/cavendish-sfh\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/cavendish-sfh\/\" style=\"color: #575959\" target=\"_self\">CAVENDISH SFH<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_6 portfolio_category_14 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-arts-barcelona\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/11\/Cover.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/11\/Cover.jpg 1080w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/11\/Cover-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/11\/Cover-1024x1024.jpg 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/11\/Cover-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/11\/Cover-768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/11\/Cover-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/11\/Cover-500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/11\/Cover-1000x1000.jpg 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/11\/Cover-700x700.jpg 700w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-arts-barcelona\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-arts-barcelona\/\" style=\"color: #575959\" target=\"_self\">HOTEL ARTS BARCELONA<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_6 portfolio_category_14 portfolio_category_32 portfolio_category_30 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/h10-montcada\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"2560\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/07\/Cuadrada_Mesa-de-trabajo-1-scaled.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/07\/Cuadrada_Mesa-de-trabajo-1-scaled.jpg 2560w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/07\/Cuadrada_Mesa-de-trabajo-1-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/07\/Cuadrada_Mesa-de-trabajo-1-1024x1024.jpg 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/07\/Cuadrada_Mesa-de-trabajo-1-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/07\/Cuadrada_Mesa-de-trabajo-1-768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/07\/Cuadrada_Mesa-de-trabajo-1-1536x1536.jpg 1536w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/07\/Cuadrada_Mesa-de-trabajo-1-2048x2048.jpg 2048w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/07\/Cuadrada_Mesa-de-trabajo-1-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/07\/Cuadrada_Mesa-de-trabajo-1-500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/07\/Cuadrada_Mesa-de-trabajo-1-1000x1000.jpg 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/07\/Cuadrada_Mesa-de-trabajo-1-700x700.jpg 700w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/h10-montcada\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/h10-montcada\/\" style=\"color: #575959\" target=\"_self\">H10 MONTCADA<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_111 portfolio_category_80 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/drama-hall\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/06\/New_Opera_House_021x1.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/06\/New_Opera_House_021x1.jpg 800w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/06\/New_Opera_House_021x1-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/06\/New_Opera_House_021x1-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/06\/New_Opera_House_021x1-768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/06\/New_Opera_House_021x1-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/06\/New_Opera_House_021x1-500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/06\/New_Opera_House_021x1-700x700.jpg 700w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/drama-hall\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/drama-hall\/\" style=\"color: #575959\" target=\"_self\">DRAMA HALL<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_6 portfolio_category_14 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/the-madrid-edition\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1050\" height=\"1050\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/05\/The-Madrid-Edition-cuadrada-1.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/05\/The-Madrid-Edition-cuadrada-1.jpg 1050w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/05\/The-Madrid-Edition-cuadrada-1-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/05\/The-Madrid-Edition-cuadrada-1-1024x1024.jpg 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/05\/The-Madrid-Edition-cuadrada-1-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/05\/The-Madrid-Edition-cuadrada-1-768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/05\/The-Madrid-Edition-cuadrada-1-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/05\/The-Madrid-Edition-cuadrada-1-500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/05\/The-Madrid-Edition-cuadrada-1-1000x1000.jpg 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/05\/The-Madrid-Edition-cuadrada-1-700x700.jpg 700w\" sizes=\"(max-width: 1050px) 100vw, 1050px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/the-madrid-edition\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/the-madrid-edition\/\" style=\"color: #575959\" target=\"_self\">THE MADRID EDITION<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_13 portfolio_category_10 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/kkv-orebro\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/04\/Cuadrado_.webp\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/04\/Cuadrado_.webp 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/04\/Cuadrado_-300x300.webp 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/04\/Cuadrado_-150x150.webp 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/kkv-orebro\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/kkv-orebro\/\" style=\"color: #575959\" target=\"_self\">KKV \u00d6REBRO<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_13 portfolio_category_10 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/swedbank\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"2560\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/04\/Portada_Mesa-de-trabajo-1-scaled.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/04\/Portada_Mesa-de-trabajo-1-scaled.jpg 2560w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/04\/Portada_Mesa-de-trabajo-1-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/04\/Portada_Mesa-de-trabajo-1-1024x1024.jpg 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/04\/Portada_Mesa-de-trabajo-1-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/04\/Portada_Mesa-de-trabajo-1-768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/04\/Portada_Mesa-de-trabajo-1-1536x1536.jpg 1536w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/04\/Portada_Mesa-de-trabajo-1-2048x2048.jpg 2048w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/04\/Portada_Mesa-de-trabajo-1-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/04\/Portada_Mesa-de-trabajo-1-500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/04\/Portada_Mesa-de-trabajo-1-1000x1000.jpg 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/04\/Portada_Mesa-de-trabajo-1-700x700.jpg 700w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/swedbank\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/swedbank\/\" style=\"color: #575959\" target=\"_self\">SWEDBANK<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_111 portfolio_category_7 portfolio_category_13 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/symbiose\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1299\" height=\"1299\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/03\/Portada.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/03\/Portada.jpg 1299w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/03\/Portada-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/03\/Portada-1024x1024.jpg 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/03\/Portada-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/03\/Portada-768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/03\/Portada-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/03\/Portada-500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/03\/Portada-1000x1000.jpg 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/03\/Portada-700x700.jpg 700w\" sizes=\"(max-width: 1299px) 100vw, 1299px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/symbiose\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/symbiose\/\" style=\"color: #575959\" target=\"_self\">SYMBIOSE<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_6 portfolio_category_15 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/aeropuerto-del-prat\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/02\/Cuadrada.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/02\/Cuadrada.jpg 1080w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/02\/Cuadrada-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/02\/Cuadrada-1024x1024.jpg 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/02\/Cuadrada-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/02\/Cuadrada-768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/02\/Cuadrada-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/02\/Cuadrada-500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/02\/Cuadrada-1000x1000.jpg 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/02\/Cuadrada-700x700.jpg 700w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/aeropuerto-del-prat\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/aeropuerto-del-prat\/\" style=\"color: #575959\" target=\"_self\">AEROPUERTO DEL PRAT<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_80 portfolio_category_9 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/museo-de-munch\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/01\/Munch-museum-sq-I.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/01\/Munch-museum-sq-I.jpg 1080w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/01\/Munch-museum-sq-I-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/01\/Munch-museum-sq-I-1024x1024.jpg 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/01\/Munch-museum-sq-I-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/01\/Munch-museum-sq-I-768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/01\/Munch-museum-sq-I-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/01\/Munch-museum-sq-I-500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/01\/Munch-museum-sq-I-1000x1000.jpg 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/01\/Munch-museum-sq-I-700x700.jpg 700w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/museo-de-munch\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/museo-de-munch\/\" style=\"color: #575959\" target=\"_self\">MUSEO DE MUNCH<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_6 portfolio_category_14 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/barcelona-edition-hotel\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/01\/Portada-2.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/01\/Portada-2.jpg 1080w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/01\/Portada-2-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/01\/Portada-2-1024x1024.jpg 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/01\/Portada-2-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/01\/Portada-2-768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/01\/Portada-2-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/01\/Portada-2-500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/01\/Portada-2-1000x1000.jpg 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/01\/Portada-2-700x700.jpg 700w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/barcelona-edition-hotel\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/barcelona-edition-hotel\/\" style=\"color: #575959\" target=\"_self\">BARCELONA EDITION<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_111 portfolio_category_7 portfolio_category_13 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/comunity\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1542\" height=\"1542\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/02\/Sin-titulo-11x1-1.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/02\/Sin-titulo-11x1-1.jpg 1542w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/02\/Sin-titulo-11x1-1-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/02\/Sin-titulo-11x1-1-1024x1024.jpg 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/02\/Sin-titulo-11x1-1-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/02\/Sin-titulo-11x1-1-768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/02\/Sin-titulo-11x1-1-1536x1536.jpg 1536w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/02\/Sin-titulo-11x1-1-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/02\/Sin-titulo-11x1-1-500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/02\/Sin-titulo-11x1-1-1000x1000.jpg 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/02\/Sin-titulo-11x1-1-700x700.jpg 700w\" sizes=\"(max-width: 1542px) 100vw, 1542px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/comunity\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/comunity\/\" style=\"color: #575959\" target=\"_self\">COM\u00b4UNITY<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_80 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/vac-moscu\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1344\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/12\/2.ph_-e1639657086123.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/vac-moscu\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/vac-moscu\/\" style=\"color: #575959\" target=\"_self\">FUNDACI\u00d3N VAC<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_5 portfolio_category_14 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-villa\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"853\" height=\"853\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/12\/PortadaVilla.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/12\/PortadaVilla.jpg 853w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/12\/PortadaVilla-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/12\/PortadaVilla-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/12\/PortadaVilla-768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/12\/PortadaVilla-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/12\/PortadaVilla-500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/12\/PortadaVilla-700x700.jpg 700w\" sizes=\"(max-width: 853px) 100vw, 853px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-villa\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-villa\/\" style=\"color: #575959\" target=\"_self\">HOTEL VILLA<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_111 portfolio_category_80 portfolio_category_13 portfolio_category_10 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/sara-kulturhus\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/09\/1X1-WEB.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/09\/1X1-WEB.jpg 1080w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/09\/1X1-WEB-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/09\/1X1-WEB-1024x1024.jpg 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/09\/1X1-WEB-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/09\/1X1-WEB-768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/09\/1X1-WEB-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/09\/1X1-WEB-500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/09\/1X1-WEB-1000x1000.jpg 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/09\/1X1-WEB-700x700.jpg 700w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/sara-kulturhus\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/sara-kulturhus\/\" style=\"color: #575959\" target=\"_self\">SARA KULTURHUS<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_5 portfolio_category_13 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/kab\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1200\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/08\/Cuadrada-II.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/08\/Cuadrada-II.jpg 1200w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/08\/Cuadrada-II-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/08\/Cuadrada-II-1024x1024.jpg 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/08\/Cuadrada-II-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/08\/Cuadrada-II-768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/08\/Cuadrada-II-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/08\/Cuadrada-II-500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/08\/Cuadrada-II-1000x1000.jpg 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/08\/Cuadrada-II-700x700.jpg 700w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/kab\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/kab\/\" style=\"color: #575959\" target=\"_self\">KAB<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_111 portfolio_category_6 portfolio_category_13 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/torre-agbar\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1064\" height=\"1064\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/05\/Cuadrada.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/05\/Cuadrada.jpg 1064w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/05\/Cuadrada-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/05\/Cuadrada-1024x1024.jpg 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/05\/Cuadrada-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/05\/Cuadrada-768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/05\/Cuadrada-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/05\/Cuadrada-500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/05\/Cuadrada-1000x1000.jpg 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/05\/Cuadrada-700x700.jpg 700w\" sizes=\"(max-width: 1064px) 100vw, 1064px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/torre-agbar\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/torre-agbar\/\" style=\"color: #575959\" target=\"_self\">TORRE AGBAR<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_15 portfolio_category_11 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/the-triangle\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/04\/Portada-.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/04\/Portada-.jpg 1080w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/04\/Portada--300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/04\/Portada--1024x1024.jpg 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/04\/Portada--150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/04\/Portada--768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/04\/Portada--570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/04\/Portada--500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/04\/Portada--1000x1000.jpg 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/04\/Portada--700x700.jpg 700w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/the-triangle\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/the-triangle\/\" style=\"color: #575959\" target=\"_self\">THE TRIANGLE<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_15 portfolio_category_10 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/biomedicum-2\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/02\/Portada.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/02\/Portada.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/02\/Portada-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/02\/Portada-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/02\/Portada-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/02\/Portada-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/biomedicum-2\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/biomedicum-2\/\" style=\"color: #575959\" target=\"_self\">BIOMEDICUM<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_111 portfolio_category_7 portfolio_category_13 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/saint-gobian\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/02\/ROOFTOP-SMALL12.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/02\/ROOFTOP-SMALL12.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/02\/ROOFTOP-SMALL12-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/02\/ROOFTOP-SMALL12-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/02\/ROOFTOP-SMALL12-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/02\/ROOFTOP-SMALL12-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/saint-gobian\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/saint-gobian\/\" style=\"color: #575959\" target=\"_self\">TORRE SAINT-GOBAIN<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_6 portfolio_category_14 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-seventy\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/12\/c-portada.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/12\/c-portada.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/12\/c-portada-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/12\/c-portada-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/12\/c-portada-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/12\/c-portada-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-seventy\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-seventy\/\" style=\"color: #575959\" target=\"_self\">HOTEL SEVENTY<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_6 portfolio_category_14 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/h10-marina\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/12\/b-portada.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/12\/b-portada.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/12\/b-portada-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/12\/b-portada-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/12\/b-portada-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/12\/b-portada-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/h10-marina\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/h10-marina\/\" style=\"color: #575959\" target=\"_self\">H10 MARINA<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_7 portfolio_category_14 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-intercontinental-paris-le-grand\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/12\/a-portada.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/12\/a-portada.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/12\/a-portada-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/12\/a-portada-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/12\/a-portada-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/12\/a-portada-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-intercontinental-paris-le-grand\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-intercontinental-paris-le-grand\/\" style=\"color: #575959\" target=\"_self\">HOTEL INTERCONTINENTAL PARIS LE GRAND<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_15 portfolio_category_11 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/queen-mary-university\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-20.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-20.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-20-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-20-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-20-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-20-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/queen-mary-university\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/queen-mary-university\/\" style=\"color: #575959\" target=\"_self\">QUEEN MARY UNIVERSITY<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_14 portfolio_category_11 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/university-arms\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-19.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-19.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-19-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-19-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-19-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-19-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/university-arms\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/university-arms\/\" style=\"color: #575959\" target=\"_self\">UNIVERSITY ARMS<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_13 portfolio_category_10 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/telenor\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/11portada.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/11portada.jpg 1080w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/11portada-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/11portada-1024x1024.jpg 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/11portada-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/11portada-768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/11portada-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/11portada-500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/11portada-1000x1000.jpg 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/11portada-700x700.jpg 700w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/telenor\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/telenor\/\" style=\"color: #575959\" target=\"_self\">TELENOR<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_13 portfolio_category_10 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/masterhuset-pembroke\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-18.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-18.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-18-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-18-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-18-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-18-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/masterhuset-pembroke\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/masterhuset-pembroke\/\" style=\"color: #575959\" target=\"_self\">M\u00c4STERHUSET PEMBROKE<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_15 portfolio_category_10 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/khm-stockholm\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-1-6.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-1-6.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-1-6-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-1-6-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-1-6-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-1-6-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/khm-stockholm\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/khm-stockholm\/\" style=\"color: #575959\" target=\"_self\">KMH STOCKHOLM<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_14 portfolio_category_10 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-hobo\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-16.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-16.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-16-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-16-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-16-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-16-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-hobo\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-hobo\/\" style=\"color: #575959\" target=\"_self\">HOTEL HOBO<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_15 portfolio_category_9 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/aeropuerto-de-bergen\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/7-2.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/7-2.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/7-2-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/7-2-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/7-2-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/7-2-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/aeropuerto-de-bergen\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/aeropuerto-de-bergen\/\" style=\"color: #575959\" target=\"_self\">AEROPUERTO DE BERGEN<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_14 portfolio_category_9 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-britannia\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-14.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-14.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-14-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-14-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-14-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-14-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-britannia\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-britannia\/\" style=\"color: #575959\" target=\"_self\">HOTEL BRITANNIA<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_111 portfolio_category_80 portfolio_category_9 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/stavanger-konserthus\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Cuadrada-II.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Cuadrada-II.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Cuadrada-II-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Cuadrada-II-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Cuadrada-II-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Cuadrada-II-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/stavanger-konserthus\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/stavanger-konserthus\/\" style=\"color: #575959\" target=\"_self\">STAVANGER KONSERTHUS<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_111 portfolio_category_80 portfolio_category_9 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/opera-de-oslo\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-1-5.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-1-5.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-1-5-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-1-5-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-1-5-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-1-5-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/opera-de-oslo\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/opera-de-oslo\/\" style=\"color: #575959\" target=\"_self\">OPERA DE OSLO<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_111 portfolio_category_80 portfolio_category_9 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/kulturvartalet-bodo\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-13.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-13.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-13-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-13-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-13-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-13-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/kulturvartalet-bodo\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/kulturvartalet-bodo\/\" style=\"color: #575959\" target=\"_self\">KULTURVARTALET BODO<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_14 portfolio_category_8 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-porto\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-12.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-12.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-12-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-12-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-12-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-12-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-porto\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-porto\/\" style=\"color: #575959\" target=\"_self\">HOTEL PORTO<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_7 portfolio_category_15 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/palacio-de-justicia-de-paris-2\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-1-4.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-1-4.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-1-4-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-1-4-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-1-4-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-1-4-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/palacio-de-justicia-de-paris-2\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/palacio-de-justicia-de-paris-2\/\" style=\"color: #575959\" target=\"_self\">PALACIO DE JUSTICIA DE PAR\u00cdS<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_7 portfolio_category_15 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/palacio-de-justicia-de-estrasburgo\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Cuadrada-2.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Cuadrada-2.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Cuadrada-2-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Cuadrada-2-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Cuadrada-2-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Cuadrada-2-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/palacio-de-justicia-de-estrasburgo\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/palacio-de-justicia-de-estrasburgo\/\" style=\"color: #575959\" target=\"_self\">PALACIO DE JUSTICIA DE ESTRASBURGO<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_7 portfolio_category_14 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-de-crillon\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-1-3.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-1-3.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-1-3-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-1-3-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-1-3-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-1-3-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-de-crillon\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-de-crillon\/\" style=\"color: #575959\" target=\"_self\">HOTEL DE CRILLON<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_7 portfolio_category_14 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-ascott-paris\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-10.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-10.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-10-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-10-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-10-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-10-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-ascott-paris\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-ascott-paris\/\" style=\"color: #575959\" target=\"_self\">HOTEL ASCOTT PAR\u00cdS<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_111 portfolio_category_80 portfolio_category_7 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/cite-musicale-paris\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/1-15.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/1-15.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/1-15-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/1-15-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/1-15-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/1-15-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/cite-musicale-paris\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/cite-musicale-paris\/\" style=\"color: #575959\" target=\"_self\">CIT\u00c9 MUSICALE PAR\u00cdS<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_6 portfolio_category_13 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/torre-puig\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-8.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-8.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-8-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-8-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-8-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-8-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/torre-puig\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/torre-puig\/\" style=\"color: #575959\" target=\"_self\">TORRE PUIG<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_6 portfolio_category_15 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/campus-generalitat\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-7.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-7.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-7-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-7-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-7-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-7-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/campus-generalitat\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/campus-generalitat\/\" style=\"color: #575959\" target=\"_self\">CAMPUS GENERALITAT<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_6 portfolio_category_14 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-princesa-sofia\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-6.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-6.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-6-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-6-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-6-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-6-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-princesa-sofia\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-princesa-sofia\/\" style=\"color: #575959\" target=\"_self\">HOTEL SOF\u00cdA<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_6 portfolio_category_14 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-hilton-diagonal-mar\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-5.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-5.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-5-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-5-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-5-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-5-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-hilton-diagonal-mar\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-hilton-diagonal-mar\/\" style=\"color: #575959\" target=\"_self\">HOTEL HILTON DIAGONAL MAR<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_6 portfolio_category_14 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/h10-the-one\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-4.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-4.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-4-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-4-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-4-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-4-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/h10-the-one\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/h10-the-one\/\" style=\"color: #575959\" target=\"_self\">H10 THE ONE<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_6 portfolio_category_14 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/h10-madison\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-3.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-3.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-3-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-3-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-3-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-3-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/h10-madison\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/h10-madison\/\" style=\"color: #575959\" target=\"_self\">H10 MADISON<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_111 portfolio_category_80 portfolio_category_6 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/palacio-euskalduna\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Auditoiro-Palacio-Euskalduna-095-PRINCIPAL1x1.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Auditoiro-Palacio-Euskalduna-095-PRINCIPAL1x1.jpg 1080w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Auditoiro-Palacio-Euskalduna-095-PRINCIPAL1x1-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Auditoiro-Palacio-Euskalduna-095-PRINCIPAL1x1-1024x1024.jpg 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Auditoiro-Palacio-Euskalduna-095-PRINCIPAL1x1-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Auditoiro-Palacio-Euskalduna-095-PRINCIPAL1x1-768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Auditoiro-Palacio-Euskalduna-095-PRINCIPAL1x1-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Auditoiro-Palacio-Euskalduna-095-PRINCIPAL1x1-500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Auditoiro-Palacio-Euskalduna-095-PRINCIPAL1x1-1000x1000.jpg 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Auditoiro-Palacio-Euskalduna-095-PRINCIPAL1x1-700x700.jpg 700w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/palacio-euskalduna\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/palacio-euskalduna\/\" style=\"color: #575959\" target=\"_self\">PALACIO EUSKALDUNA<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_111 portfolio_category_80 portfolio_category_6 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/liceu-barcelona\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1100\" height=\"1100\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/liceu_espais_0511x1.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/liceu_espais_0511x1.jpg 1100w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/liceu_espais_0511x1-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/liceu_espais_0511x1-1024x1024.jpg 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/liceu_espais_0511x1-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/liceu_espais_0511x1-768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/liceu_espais_0511x1-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/liceu_espais_0511x1-500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/liceu_espais_0511x1-1000x1000.jpg 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/liceu_espais_0511x1-700x700.jpg 700w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/liceu-barcelona\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/liceu-barcelona\/\" style=\"color: #575959\" target=\"_self\">LICEU BARCELONA<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_111 portfolio_category_5 portfolio_category_13 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/axeltorv\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/4-9.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/4-9.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/4-9-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/4-9-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/4-9-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/4-9-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/axeltorv\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/axeltorv\/\" style=\"color: #575959\" target=\"_self\">AXEL TOWERS<\/a><\/h6><\/div><\/article>\n<article class='mix portfolio_category_5 portfolio_category_15 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/aalborg-house-of-music\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"2560\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Musikkens-Hus-Profilbileder-Salen-og-Foyer-24-juli-18-20141x1-1-scaled.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Musikkens-Hus-Profilbileder-Salen-og-Foyer-24-juli-18-20141x1-1-scaled.jpg 2560w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Musikkens-Hus-Profilbileder-Salen-og-Foyer-24-juli-18-20141x1-1-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Musikkens-Hus-Profilbileder-Salen-og-Foyer-24-juli-18-20141x1-1-1024x1024.jpg 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Musikkens-Hus-Profilbileder-Salen-og-Foyer-24-juli-18-20141x1-1-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Musikkens-Hus-Profilbileder-Salen-og-Foyer-24-juli-18-20141x1-1-768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Musikkens-Hus-Profilbileder-Salen-og-Foyer-24-juli-18-20141x1-1-1536x1536.jpg 1536w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Musikkens-Hus-Profilbileder-Salen-og-Foyer-24-juli-18-20141x1-1-2048x2048.jpg 2048w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Musikkens-Hus-Profilbileder-Salen-og-Foyer-24-juli-18-20141x1-1-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Musikkens-Hus-Profilbileder-Salen-og-Foyer-24-juli-18-20141x1-1-500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Musikkens-Hus-Profilbileder-Salen-og-Foyer-24-juli-18-20141x1-1-1000x1000.jpg 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Musikkens-Hus-Profilbileder-Salen-og-Foyer-24-juli-18-20141x1-1-700x700.jpg 700w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><span class=\"feature_holder_icons\"><a itemprop='url' class='preview qbutton small white' href='https:\/\/www.frapont.es\/es\/portfolio_page\/aalborg-house-of-music\/' target='_self'>view<\/a><\/span><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description 'style=border-style:solid;'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/aalborg-house-of-music\/\" style=\"color: #575959\" target=\"_self\">AALBORG HOUSE OF MUSIC<\/a><\/h6><\/div><\/article>\n<div class='filler'><\/div>\n<div class='filler'><\/div>\n<div class='filler'><\/div>\n<div class='filler'><\/div>\n<\/div><\/div><\/div><div class=\"qode-advanced-tab-container\" id=\"tab-lista-406\" data-icon-pack=\"font_awesome\" data-icon-html=\"&lt;i class=&quot;qode_icon_font_awesome fa fa-list-ul &quot; &gt;&lt;\/i&gt;\">[vc_empty_space height=\u00bb20px\u00bb][vc_row_inner row_type=\u00bbrow\u00bb type=\u00bbgrid\u00bb text_align=\u00bbleft\u00bb css_animation=\u00bb\u00bb el_class=\u00bbnoimage-portfolio\u00bb][vc_column_inner]<div class='projects_holder_outer v1 portfolio_with_space portfolio_standard'><div class='filter_outer'><div class='filter_holder'>\n                            <ul>\n                            <li class='filter' data-filter='all'><span style='color:#9a9a9a'>All<\/span><\/li><li class='filter' data-filter='portfolio_category_111'><span style='color:#9a9a9a'>Auditorios<\/span><\/li><li class='filter' data-filter='portfolio_category_80'><span style='color:#9a9a9a'>Cultural<\/span><\/li><li class='filter' data-filter='portfolio_category_5'><span style='color:#9a9a9a'>Dinamarca<\/span><\/li><li class='filter' data-filter='portfolio_category_6'><span style='color:#9a9a9a'>Espa\u00f1a<\/span><\/li><li class='filter' data-filter='portfolio_category_7'><span style='color:#9a9a9a'>Francia<\/span><\/li><li class='filter' data-filter='portfolio_category_14'><span style='color:#9a9a9a'>Hoteles<\/span><\/li><li class='filter' data-filter='portfolio_category_15'><span style='color:#9a9a9a'>Institucional<\/span><\/li><li class='filter' data-filter='portfolio_category_8'><span style='color:#9a9a9a'>Montenegro<\/span><\/li><li class='filter' data-filter='portfolio_category_9'><span style='color:#9a9a9a'>Noruega<\/span><\/li><li class='filter' data-filter='portfolio_category_13'><span style='color:#9a9a9a'>Oficinas<\/span><\/li><li class='filter' data-filter='portfolio_category_10'><span style='color:#9a9a9a'>Suecia<\/span><\/li><li class='filter' data-filter='portfolio_category_130'><span style='color:#9a9a9a'>Suministro<\/span><\/li><li class='filter' data-filter='portfolio_category_11'><span style='color:#9a9a9a'>UK<\/span><\/li><\/ul><\/div><\/div><div class='projects_holder portfolio_main_holder clearfix v1 standard portfolio_full_image '>\n<article class='mix portfolio_category_5 portfolio_category_13 portfolio_category_130 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/suministro-paneles-acusticos-madera-copenhague\/' target='_self'><span class='image'><img fetchpriority=\"high\" decoding=\"async\" width=\"1120\" height=\"1120\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/07\/APPENSION_FRAPONT_5_web.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/07\/APPENSION_FRAPONT_5_web.jpg 1120w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/07\/APPENSION_FRAPONT_5_web-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/07\/APPENSION_FRAPONT_5_web-1024x1024.jpg 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/07\/APPENSION_FRAPONT_5_web-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/07\/APPENSION_FRAPONT_5_web-768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/07\/APPENSION_FRAPONT_5_web-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/07\/APPENSION_FRAPONT_5_web-500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/07\/APPENSION_FRAPONT_5_web-1000x1000.jpg 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/07\/APPENSION_FRAPONT_5_web-700x700.jpg 700w\" sizes=\"(max-width: 1120px) 100vw, 1120px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/suministro-paneles-acusticos-madera-copenhague\/\" style=\"color: #575959\" target=\"_self\">AP PENSION &#038; NYKREDIT<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Dinamarca, Oficinas, Suministro<\/span><\/div><\/article>\n<article class='mix portfolio_category_9 portfolio_category_13 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/escaleras-interiores-gnist-stavanger\/' target='_self'><span class='image'><img decoding=\"async\" width=\"2560\" height=\"2560\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/02\/1x1-web-scaled.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/02\/1x1-web-scaled.jpg 2560w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/02\/1x1-web-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/02\/1x1-web-1024x1024.jpg 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/02\/1x1-web-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/02\/1x1-web-768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/02\/1x1-web-1536x1536.jpg 1536w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/02\/1x1-web-2048x2048.jpg 2048w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/02\/1x1-web-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/02\/1x1-web-500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/02\/1x1-web-1000x1000.jpg 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/02\/1x1-web-700x700.jpg 700w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" loading=\"lazy\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/escaleras-interiores-gnist-stavanger\/\" style=\"color: #575959\" target=\"_self\">GNIST<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Noruega, Oficinas<\/span><\/div><\/article>\n<article class='mix portfolio_category_111 portfolio_category_80 portfolio_category_9 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/proyectos-revestimientos-acusticos-de-madera\/' target='_self'><span class='image'><img decoding=\"async\" width=\"1331\" height=\"1331\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/02\/Miniatura.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/02\/Miniatura.jpg 1331w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/02\/Miniatura-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/02\/Miniatura-1024x1024.jpg 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/02\/Miniatura-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/02\/Miniatura-768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/02\/Miniatura-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/02\/Miniatura-500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/02\/Miniatura-1000x1000.jpg 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/02\/Miniatura-700x700.jpg 700w\" sizes=\"(max-width: 1331px) 100vw, 1331px\" loading=\"lazy\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/proyectos-revestimientos-acusticos-de-madera\/\" style=\"color: #575959\" target=\"_self\">NORMORIA<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Auditorios, Cultural, Noruega<\/span><\/div><\/article>\n<article class='mix portfolio_category_6 portfolio_category_13 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/proyectos-soluciones-tecnicas-a-medida-edificio-estel\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1302\" height=\"1302\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/01\/portada-web.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/01\/portada-web.jpg 1302w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/01\/portada-web-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/01\/portada-web-1024x1024.jpg 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/01\/portada-web-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/01\/portada-web-768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/01\/portada-web-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/01\/portada-web-500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/01\/portada-web-1000x1000.jpg 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2026\/01\/portada-web-700x700.jpg 700w\" sizes=\"(max-width: 1302px) 100vw, 1302px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/proyectos-soluciones-tecnicas-a-medida-edificio-estel\/\" style=\"color: #575959\" target=\"_self\">ESTEL BARCELONA<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Espa\u00f1a, Oficinas<\/span><\/div><\/article>\n<article class='mix portfolio_category_80 portfolio_category_9 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/aahka-de-outi-pieski\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1578\" height=\"1577\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2025\/12\/Rasmus_Hjortshoj__Regjeringkvartalet_WEB-40_portada.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2025\/12\/Rasmus_Hjortshoj__Regjeringkvartalet_WEB-40_portada.png 1578w, https:\/\/www.frapont.es\/wp-content\/uploads\/2025\/12\/Rasmus_Hjortshoj__Regjeringkvartalet_WEB-40_portada-300x300.png 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2025\/12\/Rasmus_Hjortshoj__Regjeringkvartalet_WEB-40_portada-1024x1024.png 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2025\/12\/Rasmus_Hjortshoj__Regjeringkvartalet_WEB-40_portada-150x150.png 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2025\/12\/Rasmus_Hjortshoj__Regjeringkvartalet_WEB-40_portada-768x768.png 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2025\/12\/Rasmus_Hjortshoj__Regjeringkvartalet_WEB-40_portada-1536x1536.png 1536w, https:\/\/www.frapont.es\/wp-content\/uploads\/2025\/12\/Rasmus_Hjortshoj__Regjeringkvartalet_WEB-40_portada-570x570.png 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2025\/12\/Rasmus_Hjortshoj__Regjeringkvartalet_WEB-40_portada-500x500.png 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2025\/12\/Rasmus_Hjortshoj__Regjeringkvartalet_WEB-40_portada-1000x1000.png 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2025\/12\/Rasmus_Hjortshoj__Regjeringkvartalet_WEB-40_portada-700x700.png 700w\" sizes=\"(max-width: 1578px) 100vw, 1578px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/aahka-de-outi-pieski\/\" style=\"color: #575959\" target=\"_self\">&#8216;AAhkA&#8217; DE OUTI PIESKI<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Cultural, Noruega<\/span><\/div><\/article>\n<article class='mix portfolio_category_9 portfolio_category_13 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/interiores-de-madera-en-construction-city-oslo\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1707\" height=\"1707\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2025\/11\/ConstructionCity04-1-scaled-e1763551218298.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2025\/11\/ConstructionCity04-1-scaled-e1763551218298.jpg 1707w, https:\/\/www.frapont.es\/wp-content\/uploads\/2025\/11\/ConstructionCity04-1-scaled-e1763551218298-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2025\/11\/ConstructionCity04-1-scaled-e1763551218298-1024x1024.jpg 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2025\/11\/ConstructionCity04-1-scaled-e1763551218298-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2025\/11\/ConstructionCity04-1-scaled-e1763551218298-768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2025\/11\/ConstructionCity04-1-scaled-e1763551218298-1536x1536.jpg 1536w, https:\/\/www.frapont.es\/wp-content\/uploads\/2025\/11\/ConstructionCity04-1-scaled-e1763551218298-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2025\/11\/ConstructionCity04-1-scaled-e1763551218298-500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2025\/11\/ConstructionCity04-1-scaled-e1763551218298-1000x1000.jpg 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2025\/11\/ConstructionCity04-1-scaled-e1763551218298-700x700.jpg 700w\" sizes=\"(max-width: 1707px) 100vw, 1707px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/interiores-de-madera-en-construction-city-oslo\/\" style=\"color: #575959\" target=\"_self\">CONSTRUCTION CITY<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Noruega, Oficinas<\/span><\/div><\/article>\n<article class='mix portfolio_category_15 portfolio_category_10 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/skane-university-hospital-campus\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/05\/Cover.webp\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/05\/Cover.webp 1080w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/05\/Cover-300x300.webp 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/05\/Cover-1024x1024.webp 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/05\/Cover-150x150.webp 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/05\/Cover-768x768.webp 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/05\/Cover-570x570.webp 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/05\/Cover-500x500.webp 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/05\/Cover-1000x1000.webp 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/05\/Cover-700x700.webp 700w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/skane-university-hospital-campus\/\" style=\"color: #575959\" target=\"_self\">SK\u00c5NE UNIVERSITY HOSPITAL CAMPUS<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Institucional, Suecia<\/span><\/div><\/article>\n<article class='mix portfolio_category_5 portfolio_category_14 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/25-hours-copenague\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/08\/cover.webp\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/08\/cover.webp 1080w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/08\/cover-300x300.webp 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/08\/cover-1024x1024.webp 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/08\/cover-150x150.webp 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/08\/cover-768x768.webp 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/08\/cover-570x570.webp 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/08\/cover-500x500.webp 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/08\/cover-1000x1000.webp 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/08\/cover-700x700.webp 700w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/25-hours-copenague\/\" style=\"color: #575959\" target=\"_self\">25 HOURS COPENAGUE<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Dinamarca, Hoteles<\/span><\/div><\/article>\n<article class='mix portfolio_category_6 portfolio_category_14 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/formentor\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"2560\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/10\/Cover-Formentor-scaled.webp\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/10\/Cover-Formentor-scaled.webp 2560w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/10\/Cover-Formentor-300x300.webp 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/10\/Cover-Formentor-1024x1024.webp 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/10\/Cover-Formentor-150x150.webp 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/10\/Cover-Formentor-768x768.webp 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/10\/Cover-Formentor-1536x1536.webp 1536w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/10\/Cover-Formentor-2048x2048.webp 2048w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/10\/Cover-Formentor-570x570.webp 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/10\/Cover-Formentor-500x500.webp 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/10\/Cover-Formentor-1000x1000.webp 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/10\/Cover-Formentor-700x700.webp 700w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/formentor\/\" style=\"color: #575959\" target=\"_self\">FORMENTOR<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Espa\u00f1a, Hoteles<\/span><\/div><\/article>\n<article class='mix portfolio_category_6 portfolio_category_14 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/westin-palace\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1279\" height=\"1279\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/10\/Cuadrada.webp\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/10\/Cuadrada.webp 1279w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/10\/Cuadrada-300x300.webp 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/10\/Cuadrada-1024x1024.webp 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/10\/Cuadrada-150x150.webp 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/10\/Cuadrada-768x768.webp 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/10\/Cuadrada-570x570.webp 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/10\/Cuadrada-500x500.webp 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/10\/Cuadrada-1000x1000.webp 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/10\/Cuadrada-700x700.webp 700w\" sizes=\"(max-width: 1279px) 100vw, 1279px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/westin-palace\/\" style=\"color: #575959\" target=\"_self\">WESTIN PALACE<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Espa\u00f1a, Hoteles<\/span><\/div><\/article>\n<article class='mix portfolio_category_7 portfolio_category_15 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/palau_valencia-copy\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/08\/COVERI.webp\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/08\/COVERI.webp 1080w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/08\/COVERI-300x300.webp 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/08\/COVERI-1024x1024.webp 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/08\/COVERI-150x150.webp 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/08\/COVERI-768x768.webp 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/08\/COVERI-570x570.webp 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/08\/COVERI-500x500.webp 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/08\/COVERI-1000x1000.webp 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2024\/08\/COVERI-700x700.webp 700w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/palau_valencia-copy\/\" style=\"color: #575959\" target=\"_self\">SAINT-DENIS PLEYEL STATION<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Francia, Institucional<\/span><\/div><\/article>\n<article class='mix portfolio_category_111 portfolio_category_80 portfolio_category_6 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/palau-de-valencia\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/11\/Palau-de-valencia-Cuadrada.webp\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/11\/Palau-de-valencia-Cuadrada.webp 1080w, https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/11\/Palau-de-valencia-Cuadrada-300x300.webp 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/11\/Palau-de-valencia-Cuadrada-1024x1024.webp 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/11\/Palau-de-valencia-Cuadrada-150x150.webp 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/11\/Palau-de-valencia-Cuadrada-768x768.webp 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/11\/Palau-de-valencia-Cuadrada-570x570.webp 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/11\/Palau-de-valencia-Cuadrada-500x500.webp 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/11\/Palau-de-valencia-Cuadrada-1000x1000.webp 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/11\/Palau-de-valencia-Cuadrada-700x700.webp 700w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/palau-de-valencia\/\" style=\"color: #575959\" target=\"_self\">PALAU DE VALENCIA<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Auditorios, Cultural, Espa\u00f1a<\/span><\/div><\/article>\n<article class='mix portfolio_category_7 portfolio_category_14 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-carlton-cannes\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/05\/Square-2.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/05\/Square-2.jpg 1080w, https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/05\/Square-2-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/05\/Square-2-1024x1024.jpg 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/05\/Square-2-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/05\/Square-2-768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/05\/Square-2-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/05\/Square-2-500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/05\/Square-2-1000x1000.jpg 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/05\/Square-2-700x700.jpg 700w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-carlton-cannes\/\" style=\"color: #575959\" target=\"_self\">HOTEL CARLTON CANNES<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Francia, Hoteles<\/span><\/div><\/article>\n<article class='mix portfolio_category_111 portfolio_category_7 portfolio_category_13 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/tour-hekla\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/12\/Hekla-.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/12\/Hekla-.jpg 1080w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/12\/Hekla--300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/12\/Hekla--1024x1024.jpg 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/12\/Hekla--150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/12\/Hekla--768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/12\/Hekla--570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/12\/Hekla--500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/12\/Hekla--1000x1000.jpg 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/12\/Hekla--700x700.jpg 700w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/tour-hekla\/\" style=\"color: #575959\" target=\"_self\">TORRE HEKLA<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Auditorios, Francia, Oficinas<\/span><\/div><\/article>\n<article class='mix portfolio_category_15 portfolio_category_11 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/cavendish-sfh\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/01\/C.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/01\/C.jpg 1080w, https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/01\/C-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/01\/C-1024x1024.jpg 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/01\/C-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/01\/C-768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/01\/C-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/01\/C-500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/01\/C-1000x1000.jpg 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2023\/01\/C-700x700.jpg 700w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/cavendish-sfh\/\" style=\"color: #575959\" target=\"_self\">CAVENDISH SFH<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Institucional, UK<\/span><\/div><\/article>\n<article class='mix portfolio_category_6 portfolio_category_14 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-arts-barcelona\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/11\/Cover.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/11\/Cover.jpg 1080w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/11\/Cover-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/11\/Cover-1024x1024.jpg 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/11\/Cover-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/11\/Cover-768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/11\/Cover-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/11\/Cover-500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/11\/Cover-1000x1000.jpg 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/11\/Cover-700x700.jpg 700w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-arts-barcelona\/\" style=\"color: #575959\" target=\"_self\">HOTEL ARTS BARCELONA<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Espa\u00f1a, Hoteles<\/span><\/div><\/article>\n<article class='mix portfolio_category_6 portfolio_category_14 portfolio_category_32 portfolio_category_30 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/h10-montcada\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"2560\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/07\/Cuadrada_Mesa-de-trabajo-1-scaled.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/07\/Cuadrada_Mesa-de-trabajo-1-scaled.jpg 2560w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/07\/Cuadrada_Mesa-de-trabajo-1-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/07\/Cuadrada_Mesa-de-trabajo-1-1024x1024.jpg 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/07\/Cuadrada_Mesa-de-trabajo-1-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/07\/Cuadrada_Mesa-de-trabajo-1-768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/07\/Cuadrada_Mesa-de-trabajo-1-1536x1536.jpg 1536w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/07\/Cuadrada_Mesa-de-trabajo-1-2048x2048.jpg 2048w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/07\/Cuadrada_Mesa-de-trabajo-1-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/07\/Cuadrada_Mesa-de-trabajo-1-500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/07\/Cuadrada_Mesa-de-trabajo-1-1000x1000.jpg 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/07\/Cuadrada_Mesa-de-trabajo-1-700x700.jpg 700w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/h10-montcada\/\" style=\"color: #575959\" target=\"_self\">H10 MONTCADA<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Espa\u00f1a, Hoteles, Hotels, Spain<\/span><\/div><\/article>\n<article class='mix portfolio_category_111 portfolio_category_80 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/drama-hall\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/06\/New_Opera_House_021x1.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/06\/New_Opera_House_021x1.jpg 800w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/06\/New_Opera_House_021x1-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/06\/New_Opera_House_021x1-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/06\/New_Opera_House_021x1-768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/06\/New_Opera_House_021x1-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/06\/New_Opera_House_021x1-500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/06\/New_Opera_House_021x1-700x700.jpg 700w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/drama-hall\/\" style=\"color: #575959\" target=\"_self\">DRAMA HALL<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Auditorios, Cultural<\/span><\/div><\/article>\n<article class='mix portfolio_category_6 portfolio_category_14 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/the-madrid-edition\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1050\" height=\"1050\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/05\/The-Madrid-Edition-cuadrada-1.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/05\/The-Madrid-Edition-cuadrada-1.jpg 1050w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/05\/The-Madrid-Edition-cuadrada-1-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/05\/The-Madrid-Edition-cuadrada-1-1024x1024.jpg 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/05\/The-Madrid-Edition-cuadrada-1-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/05\/The-Madrid-Edition-cuadrada-1-768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/05\/The-Madrid-Edition-cuadrada-1-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/05\/The-Madrid-Edition-cuadrada-1-500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/05\/The-Madrid-Edition-cuadrada-1-1000x1000.jpg 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/05\/The-Madrid-Edition-cuadrada-1-700x700.jpg 700w\" sizes=\"(max-width: 1050px) 100vw, 1050px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/the-madrid-edition\/\" style=\"color: #575959\" target=\"_self\">THE MADRID EDITION<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Espa\u00f1a, Hoteles<\/span><\/div><\/article>\n<article class='mix portfolio_category_13 portfolio_category_10 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/kkv-orebro\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/04\/Cuadrado_.webp\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/04\/Cuadrado_.webp 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/04\/Cuadrado_-300x300.webp 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/04\/Cuadrado_-150x150.webp 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/kkv-orebro\/\" style=\"color: #575959\" target=\"_self\">KKV \u00d6REBRO<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Oficinas, Suecia<\/span><\/div><\/article>\n<article class='mix portfolio_category_13 portfolio_category_10 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/swedbank\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"2560\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/04\/Portada_Mesa-de-trabajo-1-scaled.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/04\/Portada_Mesa-de-trabajo-1-scaled.jpg 2560w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/04\/Portada_Mesa-de-trabajo-1-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/04\/Portada_Mesa-de-trabajo-1-1024x1024.jpg 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/04\/Portada_Mesa-de-trabajo-1-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/04\/Portada_Mesa-de-trabajo-1-768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/04\/Portada_Mesa-de-trabajo-1-1536x1536.jpg 1536w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/04\/Portada_Mesa-de-trabajo-1-2048x2048.jpg 2048w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/04\/Portada_Mesa-de-trabajo-1-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/04\/Portada_Mesa-de-trabajo-1-500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/04\/Portada_Mesa-de-trabajo-1-1000x1000.jpg 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/04\/Portada_Mesa-de-trabajo-1-700x700.jpg 700w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/swedbank\/\" style=\"color: #575959\" target=\"_self\">SWEDBANK<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Oficinas, Suecia<\/span><\/div><\/article>\n<article class='mix portfolio_category_111 portfolio_category_7 portfolio_category_13 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/symbiose\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1299\" height=\"1299\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/03\/Portada.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/03\/Portada.jpg 1299w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/03\/Portada-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/03\/Portada-1024x1024.jpg 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/03\/Portada-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/03\/Portada-768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/03\/Portada-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/03\/Portada-500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/03\/Portada-1000x1000.jpg 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/03\/Portada-700x700.jpg 700w\" sizes=\"(max-width: 1299px) 100vw, 1299px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/symbiose\/\" style=\"color: #575959\" target=\"_self\">SYMBIOSE<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Auditorios, Francia, Oficinas<\/span><\/div><\/article>\n<article class='mix portfolio_category_6 portfolio_category_15 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/aeropuerto-del-prat\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/02\/Cuadrada.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/02\/Cuadrada.jpg 1080w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/02\/Cuadrada-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/02\/Cuadrada-1024x1024.jpg 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/02\/Cuadrada-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/02\/Cuadrada-768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/02\/Cuadrada-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/02\/Cuadrada-500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/02\/Cuadrada-1000x1000.jpg 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/02\/Cuadrada-700x700.jpg 700w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/aeropuerto-del-prat\/\" style=\"color: #575959\" target=\"_self\">AEROPUERTO DEL PRAT<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Espa\u00f1a, Institucional<\/span><\/div><\/article>\n<article class='mix portfolio_category_80 portfolio_category_9 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/museo-de-munch\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/01\/Munch-museum-sq-I.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/01\/Munch-museum-sq-I.jpg 1080w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/01\/Munch-museum-sq-I-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/01\/Munch-museum-sq-I-1024x1024.jpg 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/01\/Munch-museum-sq-I-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/01\/Munch-museum-sq-I-768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/01\/Munch-museum-sq-I-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/01\/Munch-museum-sq-I-500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/01\/Munch-museum-sq-I-1000x1000.jpg 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/01\/Munch-museum-sq-I-700x700.jpg 700w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/museo-de-munch\/\" style=\"color: #575959\" target=\"_self\">MUSEO DE MUNCH<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Cultural, Noruega<\/span><\/div><\/article>\n<article class='mix portfolio_category_6 portfolio_category_14 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/barcelona-edition-hotel\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/01\/Portada-2.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/01\/Portada-2.jpg 1080w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/01\/Portada-2-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/01\/Portada-2-1024x1024.jpg 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/01\/Portada-2-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/01\/Portada-2-768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/01\/Portada-2-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/01\/Portada-2-500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/01\/Portada-2-1000x1000.jpg 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/01\/Portada-2-700x700.jpg 700w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/barcelona-edition-hotel\/\" style=\"color: #575959\" target=\"_self\">BARCELONA EDITION<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Espa\u00f1a, Hoteles<\/span><\/div><\/article>\n<article class='mix portfolio_category_111 portfolio_category_7 portfolio_category_13 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/comunity\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1542\" height=\"1542\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/02\/Sin-titulo-11x1-1.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/02\/Sin-titulo-11x1-1.jpg 1542w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/02\/Sin-titulo-11x1-1-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/02\/Sin-titulo-11x1-1-1024x1024.jpg 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/02\/Sin-titulo-11x1-1-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/02\/Sin-titulo-11x1-1-768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/02\/Sin-titulo-11x1-1-1536x1536.jpg 1536w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/02\/Sin-titulo-11x1-1-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/02\/Sin-titulo-11x1-1-500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/02\/Sin-titulo-11x1-1-1000x1000.jpg 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2022\/02\/Sin-titulo-11x1-1-700x700.jpg 700w\" sizes=\"(max-width: 1542px) 100vw, 1542px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/comunity\/\" style=\"color: #575959\" target=\"_self\">COM\u00b4UNITY<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Auditorios, Francia, Oficinas<\/span><\/div><\/article>\n<article class='mix portfolio_category_80 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/vac-moscu\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1344\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/12\/2.ph_-e1639657086123.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/vac-moscu\/\" style=\"color: #575959\" target=\"_self\">FUNDACI\u00d3N VAC<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Cultural<\/span><\/div><\/article>\n<article class='mix portfolio_category_5 portfolio_category_14 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-villa\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"853\" height=\"853\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/12\/PortadaVilla.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/12\/PortadaVilla.jpg 853w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/12\/PortadaVilla-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/12\/PortadaVilla-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/12\/PortadaVilla-768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/12\/PortadaVilla-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/12\/PortadaVilla-500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/12\/PortadaVilla-700x700.jpg 700w\" sizes=\"(max-width: 853px) 100vw, 853px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-villa\/\" style=\"color: #575959\" target=\"_self\">HOTEL VILLA<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Dinamarca, Hoteles<\/span><\/div><\/article>\n<article class='mix portfolio_category_111 portfolio_category_80 portfolio_category_13 portfolio_category_10 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/sara-kulturhus\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/09\/1X1-WEB.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/09\/1X1-WEB.jpg 1080w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/09\/1X1-WEB-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/09\/1X1-WEB-1024x1024.jpg 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/09\/1X1-WEB-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/09\/1X1-WEB-768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/09\/1X1-WEB-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/09\/1X1-WEB-500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/09\/1X1-WEB-1000x1000.jpg 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/09\/1X1-WEB-700x700.jpg 700w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/sara-kulturhus\/\" style=\"color: #575959\" target=\"_self\">SARA KULTURHUS<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Auditorios, Cultural, Oficinas, Suecia<\/span><\/div><\/article>\n<article class='mix portfolio_category_5 portfolio_category_13 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/kab\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1200\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/08\/Cuadrada-II.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/08\/Cuadrada-II.jpg 1200w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/08\/Cuadrada-II-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/08\/Cuadrada-II-1024x1024.jpg 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/08\/Cuadrada-II-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/08\/Cuadrada-II-768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/08\/Cuadrada-II-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/08\/Cuadrada-II-500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/08\/Cuadrada-II-1000x1000.jpg 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/08\/Cuadrada-II-700x700.jpg 700w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/kab\/\" style=\"color: #575959\" target=\"_self\">KAB<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Dinamarca, Oficinas<\/span><\/div><\/article>\n<article class='mix portfolio_category_111 portfolio_category_6 portfolio_category_13 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/torre-agbar\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1064\" height=\"1064\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/05\/Cuadrada.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/05\/Cuadrada.jpg 1064w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/05\/Cuadrada-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/05\/Cuadrada-1024x1024.jpg 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/05\/Cuadrada-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/05\/Cuadrada-768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/05\/Cuadrada-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/05\/Cuadrada-500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/05\/Cuadrada-1000x1000.jpg 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/05\/Cuadrada-700x700.jpg 700w\" sizes=\"(max-width: 1064px) 100vw, 1064px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/torre-agbar\/\" style=\"color: #575959\" target=\"_self\">TORRE AGBAR<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Auditorios, Espa\u00f1a, Oficinas<\/span><\/div><\/article>\n<article class='mix portfolio_category_15 portfolio_category_11 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/the-triangle\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/04\/Portada-.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/04\/Portada-.jpg 1080w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/04\/Portada--300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/04\/Portada--1024x1024.jpg 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/04\/Portada--150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/04\/Portada--768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/04\/Portada--570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/04\/Portada--500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/04\/Portada--1000x1000.jpg 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/04\/Portada--700x700.jpg 700w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/the-triangle\/\" style=\"color: #575959\" target=\"_self\">THE TRIANGLE<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Institucional, UK<\/span><\/div><\/article>\n<article class='mix portfolio_category_15 portfolio_category_10 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/biomedicum-2\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/02\/Portada.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/02\/Portada.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/02\/Portada-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/02\/Portada-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/02\/Portada-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/02\/Portada-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/biomedicum-2\/\" style=\"color: #575959\" target=\"_self\">BIOMEDICUM<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Institucional, Suecia<\/span><\/div><\/article>\n<article class='mix portfolio_category_111 portfolio_category_7 portfolio_category_13 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/saint-gobian\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/02\/ROOFTOP-SMALL12.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/02\/ROOFTOP-SMALL12.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/02\/ROOFTOP-SMALL12-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/02\/ROOFTOP-SMALL12-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/02\/ROOFTOP-SMALL12-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2021\/02\/ROOFTOP-SMALL12-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/saint-gobian\/\" style=\"color: #575959\" target=\"_self\">TORRE SAINT-GOBAIN<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Auditorios, Francia, Oficinas<\/span><\/div><\/article>\n<article class='mix portfolio_category_6 portfolio_category_14 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-seventy\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/12\/c-portada.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/12\/c-portada.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/12\/c-portada-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/12\/c-portada-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/12\/c-portada-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/12\/c-portada-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-seventy\/\" style=\"color: #575959\" target=\"_self\">HOTEL SEVENTY<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Espa\u00f1a, Hoteles<\/span><\/div><\/article>\n<article class='mix portfolio_category_6 portfolio_category_14 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/h10-marina\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/12\/b-portada.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/12\/b-portada.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/12\/b-portada-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/12\/b-portada-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/12\/b-portada-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/12\/b-portada-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/h10-marina\/\" style=\"color: #575959\" target=\"_self\">H10 MARINA<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Espa\u00f1a, Hoteles<\/span><\/div><\/article>\n<article class='mix portfolio_category_7 portfolio_category_14 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-intercontinental-paris-le-grand\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/12\/a-portada.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/12\/a-portada.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/12\/a-portada-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/12\/a-portada-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/12\/a-portada-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/12\/a-portada-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-intercontinental-paris-le-grand\/\" style=\"color: #575959\" target=\"_self\">HOTEL INTERCONTINENTAL PARIS LE GRAND<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Francia, Hoteles<\/span><\/div><\/article>\n<article class='mix portfolio_category_15 portfolio_category_11 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/queen-mary-university\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-20.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-20.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-20-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-20-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-20-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-20-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/queen-mary-university\/\" style=\"color: #575959\" target=\"_self\">QUEEN MARY UNIVERSITY<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Institucional, UK<\/span><\/div><\/article>\n<article class='mix portfolio_category_14 portfolio_category_11 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/university-arms\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-19.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-19.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-19-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-19-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-19-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-19-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/university-arms\/\" style=\"color: #575959\" target=\"_self\">UNIVERSITY ARMS<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Hoteles, UK<\/span><\/div><\/article>\n<article class='mix portfolio_category_13 portfolio_category_10 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/telenor\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/11portada.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/11portada.jpg 1080w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/11portada-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/11portada-1024x1024.jpg 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/11portada-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/11portada-768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/11portada-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/11portada-500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/11portada-1000x1000.jpg 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/11portada-700x700.jpg 700w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/telenor\/\" style=\"color: #575959\" target=\"_self\">TELENOR<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Oficinas, Suecia<\/span><\/div><\/article>\n<article class='mix portfolio_category_13 portfolio_category_10 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/masterhuset-pembroke\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-18.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-18.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-18-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-18-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-18-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-18-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/masterhuset-pembroke\/\" style=\"color: #575959\" target=\"_self\">M\u00c4STERHUSET PEMBROKE<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Oficinas, Suecia<\/span><\/div><\/article>\n<article class='mix portfolio_category_15 portfolio_category_10 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/khm-stockholm\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-1-6.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-1-6.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-1-6-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-1-6-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-1-6-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-1-6-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/khm-stockholm\/\" style=\"color: #575959\" target=\"_self\">KMH STOCKHOLM<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Institucional, Suecia<\/span><\/div><\/article>\n<article class='mix portfolio_category_14 portfolio_category_10 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-hobo\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-16.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-16.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-16-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-16-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-16-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-16-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-hobo\/\" style=\"color: #575959\" target=\"_self\">HOTEL HOBO<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Hoteles, Suecia<\/span><\/div><\/article>\n<article class='mix portfolio_category_15 portfolio_category_9 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/aeropuerto-de-bergen\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/7-2.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/7-2.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/7-2-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/7-2-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/7-2-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/7-2-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/aeropuerto-de-bergen\/\" style=\"color: #575959\" target=\"_self\">AEROPUERTO DE BERGEN<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Institucional, Noruega<\/span><\/div><\/article>\n<article class='mix portfolio_category_14 portfolio_category_9 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-britannia\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-14.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-14.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-14-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-14-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-14-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-14-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-britannia\/\" style=\"color: #575959\" target=\"_self\">HOTEL BRITANNIA<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Hoteles, Noruega<\/span><\/div><\/article>\n<article class='mix portfolio_category_111 portfolio_category_80 portfolio_category_9 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/stavanger-konserthus\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Cuadrada-II.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Cuadrada-II.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Cuadrada-II-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Cuadrada-II-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Cuadrada-II-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Cuadrada-II-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/stavanger-konserthus\/\" style=\"color: #575959\" target=\"_self\">STAVANGER KONSERTHUS<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Auditorios, Cultural, Noruega<\/span><\/div><\/article>\n<article class='mix portfolio_category_111 portfolio_category_80 portfolio_category_9 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/opera-de-oslo\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-1-5.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-1-5.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-1-5-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-1-5-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-1-5-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-1-5-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/opera-de-oslo\/\" style=\"color: #575959\" target=\"_self\">OPERA DE OSLO<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Auditorios, Cultural, Noruega<\/span><\/div><\/article>\n<article class='mix portfolio_category_111 portfolio_category_80 portfolio_category_9 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/kulturvartalet-bodo\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-13.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-13.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-13-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-13-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-13-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-13-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/kulturvartalet-bodo\/\" style=\"color: #575959\" target=\"_self\">KULTURVARTALET BODO<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Auditorios, Cultural, Noruega<\/span><\/div><\/article>\n<article class='mix portfolio_category_14 portfolio_category_8 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-porto\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-12.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-12.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-12-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-12-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-12-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-12-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-porto\/\" style=\"color: #575959\" target=\"_self\">HOTEL PORTO<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Hoteles, Montenegro<\/span><\/div><\/article>\n<article class='mix portfolio_category_7 portfolio_category_15 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/palacio-de-justicia-de-paris-2\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-1-4.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-1-4.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-1-4-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-1-4-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-1-4-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-1-4-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/palacio-de-justicia-de-paris-2\/\" style=\"color: #575959\" target=\"_self\">PALACIO DE JUSTICIA DE PAR\u00cdS<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Francia, Institucional<\/span><\/div><\/article>\n<article class='mix portfolio_category_7 portfolio_category_15 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/palacio-de-justicia-de-estrasburgo\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Cuadrada-2.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Cuadrada-2.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Cuadrada-2-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Cuadrada-2-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Cuadrada-2-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Cuadrada-2-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/palacio-de-justicia-de-estrasburgo\/\" style=\"color: #575959\" target=\"_self\">PALACIO DE JUSTICIA DE ESTRASBURGO<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Francia, Institucional<\/span><\/div><\/article>\n<article class='mix portfolio_category_7 portfolio_category_14 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-de-crillon\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-1-3.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-1-3.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-1-3-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-1-3-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-1-3-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-1-3-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-de-crillon\/\" style=\"color: #575959\" target=\"_self\">HOTEL DE CRILLON<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Francia, Hoteles<\/span><\/div><\/article>\n<article class='mix portfolio_category_7 portfolio_category_14 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-ascott-paris\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-10.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-10.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-10-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-10-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-10-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-10-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-ascott-paris\/\" style=\"color: #575959\" target=\"_self\">HOTEL ASCOTT PAR\u00cdS<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Francia, Hoteles<\/span><\/div><\/article>\n<article class='mix portfolio_category_111 portfolio_category_80 portfolio_category_7 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/cite-musicale-paris\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/1-15.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/1-15.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/1-15-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/1-15-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/1-15-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/1-15-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/cite-musicale-paris\/\" style=\"color: #575959\" target=\"_self\">CIT\u00c9 MUSICALE PAR\u00cdS<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Auditorios, Cultural, Francia<\/span><\/div><\/article>\n<article class='mix portfolio_category_6 portfolio_category_13 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/torre-puig\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-8.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-8.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-8-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-8-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-8-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-8-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/torre-puig\/\" style=\"color: #575959\" target=\"_self\">TORRE PUIG<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Espa\u00f1a, Oficinas<\/span><\/div><\/article>\n<article class='mix portfolio_category_6 portfolio_category_15 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/campus-generalitat\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-7.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-7.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-7-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-7-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-7-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-7-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/campus-generalitat\/\" style=\"color: #575959\" target=\"_self\">CAMPUS GENERALITAT<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Espa\u00f1a, Institucional<\/span><\/div><\/article>\n<article class='mix portfolio_category_6 portfolio_category_14 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-princesa-sofia\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-6.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-6.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-6-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-6-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-6-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-6-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-princesa-sofia\/\" style=\"color: #575959\" target=\"_self\">HOTEL SOF\u00cdA<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Espa\u00f1a, Hoteles<\/span><\/div><\/article>\n<article class='mix portfolio_category_6 portfolio_category_14 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-hilton-diagonal-mar\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-5.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-5.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-5-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-5-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-5-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-5-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/hotel-hilton-diagonal-mar\/\" style=\"color: #575959\" target=\"_self\">HOTEL HILTON DIAGONAL MAR<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Espa\u00f1a, Hoteles<\/span><\/div><\/article>\n<article class='mix portfolio_category_6 portfolio_category_14 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/h10-the-one\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-4.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-4.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-4-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-4-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-4-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-4-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/h10-the-one\/\" style=\"color: #575959\" target=\"_self\">H10 THE ONE<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Espa\u00f1a, Hoteles<\/span><\/div><\/article>\n<article class='mix portfolio_category_6 portfolio_category_14 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/h10-madison\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-3.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-3.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-3-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-3-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-3-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/portada-min-3-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/h10-madison\/\" style=\"color: #575959\" target=\"_self\">H10 MADISON<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Espa\u00f1a, Hoteles<\/span><\/div><\/article>\n<article class='mix portfolio_category_111 portfolio_category_80 portfolio_category_6 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/palacio-euskalduna\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Auditoiro-Palacio-Euskalduna-095-PRINCIPAL1x1.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Auditoiro-Palacio-Euskalduna-095-PRINCIPAL1x1.jpg 1080w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Auditoiro-Palacio-Euskalduna-095-PRINCIPAL1x1-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Auditoiro-Palacio-Euskalduna-095-PRINCIPAL1x1-1024x1024.jpg 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Auditoiro-Palacio-Euskalduna-095-PRINCIPAL1x1-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Auditoiro-Palacio-Euskalduna-095-PRINCIPAL1x1-768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Auditoiro-Palacio-Euskalduna-095-PRINCIPAL1x1-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Auditoiro-Palacio-Euskalduna-095-PRINCIPAL1x1-500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Auditoiro-Palacio-Euskalduna-095-PRINCIPAL1x1-1000x1000.jpg 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Auditoiro-Palacio-Euskalduna-095-PRINCIPAL1x1-700x700.jpg 700w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/palacio-euskalduna\/\" style=\"color: #575959\" target=\"_self\">PALACIO EUSKALDUNA<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Auditorios, Cultural, Espa\u00f1a<\/span><\/div><\/article>\n<article class='mix portfolio_category_111 portfolio_category_80 portfolio_category_6 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/liceu-barcelona\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"1100\" height=\"1100\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/liceu_espais_0511x1.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/liceu_espais_0511x1.jpg 1100w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/liceu_espais_0511x1-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/liceu_espais_0511x1-1024x1024.jpg 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/liceu_espais_0511x1-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/liceu_espais_0511x1-768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/liceu_espais_0511x1-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/liceu_espais_0511x1-500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/liceu_espais_0511x1-1000x1000.jpg 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/liceu_espais_0511x1-700x700.jpg 700w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/liceu-barcelona\/\" style=\"color: #575959\" target=\"_self\">LICEU BARCELONA<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Auditorios, Cultural, Espa\u00f1a<\/span><\/div><\/article>\n<article class='mix portfolio_category_111 portfolio_category_5 portfolio_category_13 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/axeltorv\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"637\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/4-9.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/4-9.jpg 636w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/4-9-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/4-9-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/4-9-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/4-9-500x500.jpg 500w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/axeltorv\/\" style=\"color: #575959\" target=\"_self\">AXEL TOWERS<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Auditorios, Dinamarca, Oficinas<\/span><\/div><\/article>\n<article class='mix portfolio_category_5 portfolio_category_15 ' style=''><div class='image_holder'><a itemprop='url' class='portfolio_link_for_touch' href='https:\/\/www.frapont.es\/es\/portfolio_page\/aalborg-house-of-music\/' target='_self'><span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"2560\" src=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Musikkens-Hus-Profilbileder-Salen-og-Foyer-24-juli-18-20141x1-1-scaled.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Musikkens-Hus-Profilbileder-Salen-og-Foyer-24-juli-18-20141x1-1-scaled.jpg 2560w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Musikkens-Hus-Profilbileder-Salen-og-Foyer-24-juli-18-20141x1-1-300x300.jpg 300w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Musikkens-Hus-Profilbileder-Salen-og-Foyer-24-juli-18-20141x1-1-1024x1024.jpg 1024w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Musikkens-Hus-Profilbileder-Salen-og-Foyer-24-juli-18-20141x1-1-150x150.jpg 150w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Musikkens-Hus-Profilbileder-Salen-og-Foyer-24-juli-18-20141x1-1-768x768.jpg 768w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Musikkens-Hus-Profilbileder-Salen-og-Foyer-24-juli-18-20141x1-1-1536x1536.jpg 1536w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Musikkens-Hus-Profilbileder-Salen-og-Foyer-24-juli-18-20141x1-1-2048x2048.jpg 2048w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Musikkens-Hus-Profilbileder-Salen-og-Foyer-24-juli-18-20141x1-1-570x570.jpg 570w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Musikkens-Hus-Profilbileder-Salen-og-Foyer-24-juli-18-20141x1-1-500x500.jpg 500w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Musikkens-Hus-Profilbileder-Salen-og-Foyer-24-juli-18-20141x1-1-1000x1000.jpg 1000w, https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/Musikkens-Hus-Profilbileder-Salen-og-Foyer-24-juli-18-20141x1-1-700x700.jpg 700w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/span><\/a><span class='text_holder'><span class='text_outer'><span class='text_inner'><span class='feature_holder'><\/span><\/span><\/span><\/span><\/div><div class='portfolio_description text_align_left'><h6 itemprop=\"name\" class=\"portfolio_title entry_title\"><a itemprop=\"url\" href=\"https:\/\/www.frapont.es\/es\/portfolio_page\/aalborg-house-of-music\/\" style=\"color: #575959\" target=\"_self\">AALBORG HOUSE OF MUSIC<\/a><\/h6><span class=\"project_category\" style=\"color: #575959\">Dinamarca, Institucional<\/span><\/div><\/article>\n<\/div><\/div>[\/vc_column_inner][\/vc_row_inner]<\/div><div class=\"qode-advanced-tab-container\" id=\"tab-mapa-55\" data-icon-pack=\"font_awesome\" data-icon-html=\"&lt;i class=&quot;qode_icon_font_awesome fa fa-map-o &quot; &gt;&lt;\/i&gt;\">[vc_row_inner row_type=\u00bbrow\u00bb type=\u00bbfull_width\u00bb text_align=\u00bbleft\u00bb css_animation=\u00bb\u00bb][vc_column_inner][vc_column_text]<div id=\"mapplic-id692\" data-mapdata=\"{&quot;mapwidth&quot;:&quot;1200&quot;,&quot;mapheight&quot;:&quot;1200&quot;,&quot;minimap&quot;:false,&quot;zoombuttons&quot;:true,&quot;sidebar&quot;:false,&quot;search&quot;:false,&quot;hovertip&quot;:true,&quot;fullscreen&quot;:false,&quot;zoomlimit&quot;:&quot;2&quot;,&quot;mapfill&quot;:true,&quot;zoom&quot;:true,&quot;alphabetic&quot;:true,&quot;categories&quot;:[],&quot;levels&quot;:[{&quot;id&quot;:&quot;europe&quot;,&quot;title&quot;:&quot;Europe&quot;,&quot;map&quot;:&quot;\/\/www.frapont.es\/wp-content\/plugins\/mapplic\/maps\/europe.svg&quot;,&quot;minimap&quot;:&quot;https:\/\/www.frapont.es\/wp-content\/plugins\/mapplic\/maps\/europe-mini.jpg&quot;,&quot;locations&quot;:[{&quot;id&quot;:&quot;se&quot;,&quot;title&quot;:&quot;Suecia_&quot;,&quot;description&quot;:&quot;&lt;p&gt;&lt;a class=\\&quot;botonmapa\\&quot; href=\\&quot;?page_id=867\\&quot;&gt;Ver m&aacute;s&lt;\/a&gt;&lt;\/p&gt;&quot;,&quot;pin&quot;:&quot;pin-image&quot;,&quot;fill&quot;:&quot;#948a54&quot;,&quot;thumbnail&quot;:&quot;https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/icon-map.png&quot;,&quot;action&quot;:&quot;default&quot;,&quot;x&quot;:&quot;0.5073&quot;,&quot;y&quot;:&quot;0.2454&quot;},{&quot;id&quot;:&quot;fi&quot;,&quot;title&quot;:&quot;Noruega_&quot;,&quot;description&quot;:&quot;&lt;p&gt;&lt;a class=\\&quot;botonmapa\\&quot; href=\\&quot;?page_id=865\\&quot;&gt;Ver m&aacute;s&lt;\/a&gt;&lt;\/p&gt;&quot;,&quot;pin&quot;:&quot;pin-image&quot;,&quot;fill&quot;:&quot;#948a54&quot;,&quot;thumbnail&quot;:&quot;https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/icon-map.png&quot;,&quot;action&quot;:&quot;default&quot;,&quot;x&quot;:&quot;0.4240&quot;,&quot;y&quot;:&quot;0.2774&quot;},{&quot;id&quot;:&quot;fr&quot;,&quot;title&quot;:&quot;Francia_&quot;,&quot;description&quot;:&quot;&lt;p&gt;&lt;a class=\\&quot;botonmapa\\&quot; href=\\&quot;?page_id=861\\&quot;&gt;Ver m&aacute;s&lt;\/a&gt;&lt;\/p&gt;&quot;,&quot;pin&quot;:&quot;pin-image&quot;,&quot;fill&quot;:&quot;#948a54&quot;,&quot;thumbnail&quot;:&quot;https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/icon-map.png&quot;,&quot;action&quot;:&quot;default&quot;,&quot;x&quot;:&quot;0.3194&quot;,&quot;y&quot;:&quot;0.6253&quot;},{&quot;id&quot;:&quot;es&quot;,&quot;title&quot;:&quot;Espa&ntilde;a_&quot;,&quot;description&quot;:&quot;&lt;p&gt;&lt;a class=\\&quot;botonmapa\\&quot; href=\\&quot;?page_id=859\\&quot;&gt;Ver m&aacute;s&lt;\/a&gt;&lt;\/p&gt;&quot;,&quot;pin&quot;:&quot;pin-image&quot;,&quot;fill&quot;:&quot;#948a54&quot;,&quot;thumbnail&quot;:&quot;https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/icon-map.png&quot;,&quot;action&quot;:&quot;default&quot;,&quot;x&quot;:&quot;0.1892&quot;,&quot;y&quot;:&quot;0.7731&quot;},{&quot;id&quot;:&quot;gb&quot;,&quot;title&quot;:&quot;UK_&quot;,&quot;description&quot;:&quot;&lt;p&gt;&lt;a class=\\&quot;botonmapa\\&quot; href=\\&quot;?page_id=869\\&quot;&gt;Ver m&aacute;s&lt;\/a&gt;&lt;\/p&gt;&quot;,&quot;pin&quot;:&quot;pin-image&quot;,&quot;fill&quot;:&quot;#948a54&quot;,&quot;thumbnail&quot;:&quot;https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/icon-map.png&quot;,&quot;action&quot;:&quot;default&quot;,&quot;x&quot;:&quot;0.2693&quot;,&quot;y&quot;:&quot;0.4599&quot;},{&quot;id&quot;:&quot;dk&quot;,&quot;title&quot;:&quot;Dinamarca_&quot;,&quot;pin&quot;:&quot;pin-image&quot;,&quot;fill&quot;:&quot;#948a54&quot;,&quot;thumbnail&quot;:&quot;https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/icon-map.png&quot;,&quot;action&quot;:&quot;default&quot;,&quot;x&quot;:&quot;0.4603&quot;,&quot;y&quot;:&quot;0.4130&quot;,&quot;description&quot;:&quot;&lt;p&gt;&lt;a class=\\&quot;botonmapa\\&quot; href=\\&quot;?page_id=845\\&quot;&gt;Ver m&aacute;s&lt;\/a&gt;&lt;\/p&gt;&quot;},{&quot;id&quot;:&quot;me&quot;,&quot;title&quot;:&quot;Montenegro_&quot;,&quot;description&quot;:&quot;&lt;p&gt;&lt;a class=\\&quot;botonmapa\\&quot; href=\\&quot;?page_id=863\\&quot;&gt;Ver m&aacute;s&lt;\/a&gt;&lt;\/p&gt;&quot;,&quot;pin&quot;:&quot;pin-image&quot;,&quot;fill&quot;:&quot;#948a54&quot;,&quot;thumbnail&quot;:&quot;https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/icon-map.png&quot;,&quot;action&quot;:&quot;default&quot;,&quot;x&quot;:&quot;0.6030&quot;,&quot;y&quot;:&quot;0.7250&quot;},{&quot;id&quot;:&quot;ru&quot;,&quot;title&quot;:&quot;Rusia_&quot;,&quot;description&quot;:&quot;&lt;p&gt;&lt;a class=\\&quot;botonmapa\\&quot; href=\\&quot;?page_id=869\\&quot;&gt;Ver m&aacute;s&lt;\/a&gt;&lt;\/p&gt;&quot;,&quot;pin&quot;:&quot;pin-image&quot;,&quot;action&quot;:&quot;default&quot;,&quot;x&quot;:&quot;0.8233&quot;,&quot;y&quot;:&quot;0.3804&quot;}]}],&quot;maxscale&quot;:&quot;2&quot;,&quot;clearbutton&quot;:true,&quot;mousewheel&quot;:false,&quot;deeplinking&quot;:true,&quot;fillcolor&quot;:&quot;#948a54&quot;,&quot;action&quot;:&quot;tooltip&quot;,&quot;zoomoutclose&quot;:true,&quot;closezoomout&quot;:true,&quot;thumbholder&quot;:false,&quot;hidenofilter&quot;:false,&quot;linknewtab&quot;:false,&quot;csv&quot;:&quot;&quot;,&quot;topLat&quot;:&quot;&quot;,&quot;leftLng&quot;:&quot;&quot;,&quot;bottomLat&quot;:&quot;&quot;,&quot;rightLng&quot;:&quot;&quot;,&quot;height&quot;:&quot;600&quot;}\" data-height=\"650\"><\/div>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner]<\/div><\/div>[\/vc_column][\/vc_row][vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbfull_width\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb][vc_column][vc_empty_space height=\u00bb40px\u00bb][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbfull_width\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb z_index=\u00bb\u00bb][vc_column][\/vc_column][\/vc_row][vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbfull_width\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"full_width.php","meta":{"footnotes":""},"class_list":["post-100","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Proyectos &#8211; Frapont<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.frapont.es\/es\/our-projects\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Proyectos &#8211; Frapont\" \/>\n<meta property=\"og:description\" content=\"[vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbfull_width\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb z_index=\u00bb\u00bb][vc_column][\/vc_column][\/vc_row][vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbfull_width\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.frapont.es\/es\/our-projects\/\" \/>\n<meta property=\"og:site_name\" content=\"Frapont\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Frapont\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-09T08:18:59+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.frapont.es\\\/es\\\/our-projects\\\/\",\"url\":\"https:\\\/\\\/www.frapont.es\\\/es\\\/our-projects\\\/\",\"name\":\"Proyectos &#8211; Frapont\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.frapont.es\\\/#website\"},\"datePublished\":\"2018-02-06T10:46:57+00:00\",\"dateModified\":\"2026-03-09T08:18:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.frapont.es\\\/es\\\/our-projects\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.frapont.es\\\/es\\\/our-projects\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.frapont.es\\\/es\\\/our-projects\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.frapont.es\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Proyectos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.frapont.es\\\/#website\",\"url\":\"https:\\\/\\\/www.frapont.es\\\/\",\"name\":\"Frapont\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.frapont.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.frapont.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.frapont.es\\\/#organization\",\"name\":\"Frapont\",\"url\":\"https:\\\/\\\/www.frapont.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.frapont.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.frapont.es\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/logo-nav-negro-min.png\",\"contentUrl\":\"https:\\\/\\\/www.frapont.es\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/logo-nav-negro-min.png\",\"width\":235,\"height\":59,\"caption\":\"Frapont\"},\"image\":{\"@id\":\"https:\\\/\\\/www.frapont.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Frapont\\\/\",\"https:\\\/\\\/www.instagram.com\\\/frapont_wood_works\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/1739273\\\/admin\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Proyectos &#8211; Frapont","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.frapont.es\/es\/our-projects\/","og_locale":"es_ES","og_type":"article","og_title":"Proyectos &#8211; Frapont","og_description":"[vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbfull_width\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb z_index=\u00bb\u00bb][vc_column][\/vc_column][\/vc_row][vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbfull_width\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb...","og_url":"https:\/\/www.frapont.es\/es\/our-projects\/","og_site_name":"Frapont","article_publisher":"https:\/\/www.facebook.com\/Frapont\/","article_modified_time":"2026-03-09T08:18:59+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.frapont.es\/es\/our-projects\/","url":"https:\/\/www.frapont.es\/es\/our-projects\/","name":"Proyectos &#8211; Frapont","isPartOf":{"@id":"https:\/\/www.frapont.es\/#website"},"datePublished":"2018-02-06T10:46:57+00:00","dateModified":"2026-03-09T08:18:59+00:00","breadcrumb":{"@id":"https:\/\/www.frapont.es\/es\/our-projects\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.frapont.es\/es\/our-projects\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.frapont.es\/es\/our-projects\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.frapont.es\/es\/"},{"@type":"ListItem","position":2,"name":"Proyectos"}]},{"@type":"WebSite","@id":"https:\/\/www.frapont.es\/#website","url":"https:\/\/www.frapont.es\/","name":"Frapont","description":"","publisher":{"@id":"https:\/\/www.frapont.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.frapont.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.frapont.es\/#organization","name":"Frapont","url":"https:\/\/www.frapont.es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.frapont.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/logo-nav-negro-min.png","contentUrl":"https:\/\/www.frapont.es\/wp-content\/uploads\/2019\/11\/logo-nav-negro-min.png","width":235,"height":59,"caption":"Frapont"},"image":{"@id":"https:\/\/www.frapont.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Frapont\/","https:\/\/www.instagram.com\/frapont_wood_works\/","https:\/\/www.linkedin.com\/company\/1739273\/admin\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.frapont.es\/es\/wp-json\/wp\/v2\/pages\/100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.frapont.es\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.frapont.es\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.frapont.es\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.frapont.es\/es\/wp-json\/wp\/v2\/comments?post=100"}],"version-history":[{"count":50,"href":"https:\/\/www.frapont.es\/es\/wp-json\/wp\/v2\/pages\/100\/revisions"}],"predecessor-version":[{"id":91337,"href":"https:\/\/www.frapont.es\/es\/wp-json\/wp\/v2\/pages\/100\/revisions\/91337"}],"wp:attachment":[{"href":"https:\/\/www.frapont.es\/es\/wp-json\/wp\/v2\/media?parent=100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}